{"id":528,"date":"2020-12-21T07:46:46","date_gmt":"2020-12-21T07:46:46","guid":{"rendered":"http:\/\/arianpleroma.com\/?p=528"},"modified":"2020-12-21T07:46:46","modified_gmt":"2020-12-21T07:46:46","slug":"shaan","status":"publish","type":"post","link":"https:\/\/arianpleroma.com\/de\/2020\/12\/21\/shaan\/","title":{"rendered":"Shaan"},"content":{"rendered":"<p>Shaan das Wunderkind \u00fcberragte alle seine Altersgenossen in vielen Disziplinen wurde dann pers\u00f6nlicher Sch\u00fcler des Meisters Suryanshu, der ihn ihn die Geheimnisse der okkulten Disziplin der Wandel zwischen den Welten initiierte.<\/p>\n<p>Doch sieht er sich mit einem schweren Karma konfrontiert. In seinem letzten Leben verfiel er als reicher Unternehmer den Verf\u00fchrungen der dunklen Bruderschaft. So sind seine Lebenspfade verstrickt mit den Greifarmen der Gro\u00dfstadt. Es wirkt ein dunkler Schatten seiner vergangenen Gr\u00e4ueltaten. Wissend um die Gesetze des Karmas, sieht er sich beinahe unausweichlich einem tragischen Schicksal ergeben.<br \/>\nNach einem Absturz mit dem Gleiter trifft er auf Zoey ein Gefl\u00fcchtete aus der Gro\u00dfstadt. Ein ewiger Bund verbindet die Beiden und er versucht alles sie ihre Seele zu heilen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Shaan das Wunderkind \u00fcberragte alle seine Altersgenossen in vielen Disziplinen wurde dann pers\u00f6nlicher Sch\u00fcler des Meisters Suryanshu, der ihn ihn die Geheimnisse der okkulten Disziplin der Wandel zwischen den Welten initiierte. Doch sieht er sich mit einem schweren Karma konfrontiert. In seinem letzten Leben verfiel &hellip; <a href=\"https:\/\/arianpleroma.com\/de\/2020\/12\/21\/shaan\/\" class=\"more-link\"><span>Continue reading<span class=\"screen-reader-text\">Shaan<\/span><\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44],"tags":[],"_links":{"self":[{"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/posts\/528"}],"collection":[{"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":2,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/posts\/528\/revisions\/603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/media\/544"}],"wp:attachment":[{"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arianpleroma.com\/de\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}